{"id":107,"date":"2008-03-05T17:42:54","date_gmt":"2008-03-05T15:42:54","guid":{"rendered":"http:\/\/michauko.org\/blog\/2008\/03\/05\/statistiques-de-greylisting\/"},"modified":"2009-10-08T15:26:32","modified_gmt":"2009-10-08T13:26:32","slug":"statistiques-de-greylisting","status":"publish","type":"post","link":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/","title":{"rendered":"Statistiques de greylisting"},"content":{"rendered":"<p>Pour ceux qui ne connaissent pas, le \u00ab\u00a0Greylisting\u00a0\u00bb est un m\u00e9canisme utile et extr\u00eamement simple \u00e0 mettre en oeuvre pour r\u00e9duire significativement le nombre de spams en entr\u00e9e des serveurs de mails, sans m\u00eame avoir besoin de les analyser. En gros, vous pouvez diviser par 10 vos mails entrants et le boulot de votre spamassassin, du coup.<br \/>\nMagique ? non, logique.<br \/>\nJe vous propose dans cet article un r\u00e9sultat chiffr\u00e9 sur une installation comptant un backup MX, un frontal (qui encaisse les tentatives d&rsquo;abus etc + analyse virus) relayant enfin \u00e0 un serveur final (backend) faisant tourner un bon gros spamassassin\/SARE des familles avant la distribution du courrier. Le tout pour desservir 150 utilisateurs et\/ou bo\u00eetes mails environ (sans compter des vieux comptent qui n&rsquo;existent plus et que les spammeurs doivent avoir encore \u00ab\u00a0en t\u00eate\u00a0\u00bb).<br \/>\nLa mise en place du greylisting pour postfix est d\u00e9taill\u00e9e dans <a href=\"https:\/\/michauko.org\/docs\/debian_testing\/\">ma doc<\/a>, il ne manque qu&rsquo;une indication : d\u00e9marrer le service postgrey apr\u00e8s installation \ud83d\ude42<!--more--><\/p>\n<h3>Informations en pr\u00e9ambule<\/h3>\n<p>Les impacts pour l&rsquo;utilisateur sont minimes : d\u00e9lai d&rsquo;environ 30 minutes (en th\u00e9orie 5 minutes) lors des x (x = 5 par d\u00e9faut) premiers \u00e9changes entrants avec un serveur donn\u00e9. L&rsquo;article <a href=\"http:\/\/en.wikipedia.org\/wiki\/Greylisting\">anglais sur wikipedia<\/a> se veut un peu plus m\u00e9fiant que sa <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Greylisting\">traduction minimaliste en fran\u00e7ais<\/a>. A vous de voir. L&rsquo;autre risque serait de se retrouver face \u00e0 un vieux serveur de mails tout pourri qui impl\u00e9mente mal le protocole&#8230; boarf, je doute que \u00e7a arrive dans la pratique. Au pire l&rsquo;utilisateur verra le probl\u00e8me et il sera temps de whitelister ledit serveur.<\/p>\n<h3>Principe<\/h3>\n<p>Le principe  &#8211; je vous renvois \u00e0 l&rsquo;article wikipedia pour plus de d\u00e9tails &#8211; est d&rsquo;utiliser <strong>une fonction standard du procotole SMTP<\/strong> pour redemander l&rsquo;envoi d&rsquo;un mail lorsqu&rsquo;on le re\u00e7oit. On indique au serveur de renvoyer le message dans 5 minutes. Deux options : le serveur en face le fait, ou non. Au bout de x fois &#8211; si le serveur s&rsquo;est bien comport\u00e9 &#8211; on le \u00ab\u00a0whiteliste\u00a0\u00bb pour de bon et il n&rsquo;y aura plus de d\u00e9lai pour celui-ci.<\/p>\n<h3>Quel lien avec les spammeurs ?<\/h3>\n<p>Imaginez une arm\u00e9e de PC <s>(windows)<\/s> zombies envoyant des mails \u00e0 tout va (\u00e0 l&rsquo;insu de l&rsquo;utilisateur, forc\u00e9ment). Le zombie utilise un programme le plus simple possible qui se contente d&rsquo;envoyer la pur\u00e9e. De toute mani\u00e8re, un PC zombie comme de ce type n&rsquo;a en g\u00e9n\u00e9ral pas de lien retour possible vers lui m\u00eame sur le port 25 (pensez \u00e0 votre PC derri\u00e8re un routeur genre freebox). Donc il ne recevra jamais votre demande standard de renvoi de mails. Et donc vous n&rsquo;aurez jamais le mail, qui \u00e9tait un spam \u00e0 coup s\u00fbr. CQFD.<br \/>\nLisez plus bas dans l&rsquo;article quelques extraits d&rsquo;adresses \u00ab\u00a0greylist\u00e9es\u00a0\u00bb, vous comprendrez que des zombies, il y en a des millions sur la plan\u00e8te&#8230; que fait Buffy ???<br \/>\nReste ensuite les *vrais* spammeurs. Je ne sais pas dire si beaucoup d&rsquo;entre eux utilisent des serveurs standard de mails. Ceux qui n&rsquo;ont pas pr\u00e9vu le coup en tout cas, ils passent aussi \u00e0 la benne. Les autres, je ne sais pas s&rsquo;ils perdent du temps \u00e0 renvoyer la pur\u00e9e alors que des gens mal prot\u00e9g\u00e9s, il y en a tant d&rsquo;autres&#8230;<br \/>\nAlors, en attendant que les zombies prennent en charge correctement le protocole et fasse des contournements r\u00e9seaux compliqu\u00e9s (impossible ?), le greylisting peut vous aider.<\/p>\n<h3>L\u00e9ger pr\u00e9-requis sur les backups MX<\/h3>\n<p>Derni\u00e8re petite remarque en pr\u00e9ambule : il faut que tous vos serveurs frontaux (donc les backups MX) impl\u00e9mentent le greylisting !!! Donc oubliez les backups gracieusement offerts par votre fournisseur\/h\u00e9bergeur etc. En g\u00e9n\u00e9ral ils ne le font pas. Si vous avez un tel backup MX &#8211; par pseudo-s\u00e9curit\u00e9 &#8211; il est en g\u00e9n\u00e9ral d\u00e9clar\u00e9 de faible priorit\u00e9 et c&rsquo;est justement celui qui est d&rsquo;abord vis\u00e9 par les envois de spammeurs car on n&rsquo;a moins souvent la main dessus. S&rsquo;il ne greyliste pas, alors il enverra tout \u00e0 votre MX principal qui acceptera sans broncher. Le greylisting ne servira pas \u00e0 grand chose dans ce cas.<br \/>\n(Tiens, \u00e7a me fait penser \u00e0 une technique qui consiste \u00e0 utiliser un serveur inexistant comme MX de plus faible priorit\u00e9. Faudra que je teste \u00e7a un jour. Si quelqu&rsquo;un a un retour, je suis preneur)<\/p>\n<h3>Graphiques apr\u00e8s plusieurs semaines d&rsquo;utilisation<\/h3>\n<p>Plut\u00f4t qu&rsquo;un long discours, quelques dessins. Je vous laisse deviner la date de mise en place&#8230;<\/p>\n<p>Sur le frontal (MX primaire) :<br \/>\n<a href='https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png' title='Greylisting sur le frontal'><img src='https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png' alt='Greylisting sur le frontal' \/><\/a><\/p>\n<p>Et sur le backend (qui identifie les spams une fois le mail accept\u00e9) :<br \/>\n<a href='https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey2.png' title='Greylisting sur le backend'><img src='https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey2.png' alt='Greylisting sur le backend' \/><\/a><\/p>\n<h3>En chiffres<\/h3>\n<p>Avec quelques chiffres moyens pris avant et apr\u00e8s le greylisting (ceux sur le graphe sont pris \u00ab\u00a0pendant\u00a0\u00bb la mise en place, donc une moyenne d&rsquo;avant\/apr\u00e8s, pas terrible), \u00e7a donne \u00e7a :<br \/>\n&#8211; Sur le frontal, avant, on recevait environ 9,5 msg\/min et on rejetait 1\/3 (tentatives d&rsquo;openrelay, destinataires bidon etc). Maintenant, on en re\u00e7oit 3,2 par minute, toujours 1\/3 de rejet pour les m\u00eames motifs.<br \/>\n&#8211; Sur le backend du coup, il y a une sacr\u00e9e chute d&rsquo;occupation CPU par \u00ab\u00a0spamd\u00a0\u00bb et on identifie 0,6 msg\/min contre 6 par minute avant (m\u00eame taux de faux-positifs ou d&rsquo;oubli, \u00e0 savoir presque nul).<br \/>\n&#8211; En une semaine, ce ne sont pas moins de 137000 \u00ab\u00a0serveurs\u00a0\u00bb (zombies) qui ont \u00e9t\u00e9 greylist\u00e9s, avec des charmants noms comme :<\/p>\n<pre>         0x50a1511f.hknxx3.adsl-dhcp.tele.dk[80.161.81.31] 2 Time(s)\r\n         0x50a403bf.abnxx10.adsl-dhcp.tele.dk[80.164.3.191] 2 Time(s)\r\n         103.95.119-80.rev.gaoland.net[80.119.95.103] 4 Time(s)\r\n         12-208-209-2.client.mchsi.com[12.208.209.2] 2 Time(s)\r\n         12-219-39-94.client.mchsi.com[12.219.39.94] 2 Time(s)\r\n         124-171-184-145.dyn.iinet.net.au[124.171.184.145] 2 Time(s)\r\n         129-28-235-201.fibertel.com.ar[201.235.28.129] 2 Time(s)\r\n         131.201.218.87.dynamic.jazztel.es[87.218.201.131] 2 Time(s)\r\n         131.206.50.60.cbj04-home.tm.net.my[60.50.206.131] 2 Time(s)\r\n         1434933186.ip2long.net[85.135.87.194] 2 Time(s)\r\n         149.pool85-49-8.dynamic.orange.es[85.49.8.149] 2 Time(s)\r\n         1503021874.dhcp.dbnet.dk[89.150.75.50] 4 Time(s)\r\n         152-60.go.evo.bg[85.217.152.60] 2 Time(s)\r\n         156-90-99-58-T-tdtv.tinp.net.tw[58.99.90.156] 2 Time(s)\r\n         167-68-246-201.adsl.terra.cl[201.246.68.167] 2 Time(s)\r\n         168-226-244-166.mrse.com.ar[168.226.244.166] 2 Time(s)\r\n...\r\n         adsl-67-114-84-118.dsl.lsan03.pacbell.net[67.114.84.118] 2 Time(s)\r\n         adsl-68-23-4-190.dsl.ipltin.ameritech.net[68.23.4.190] 2 Time(s)\r\n         adsl-69-209-147-42.dsl.sfldmi.ameritech.net[69.209.147.42] 2 Time(s)\r\n         adsl-69-209-154-96.dsl.sfldmi.ameritech.net[69.209.154.96] 2 Time(s)\r\n...\r\n         host234-234-static.116-81-b.business.telecomitalia.it[81.116.234.234] 2 Time(s)\r\n         host241-167-dynamic.19-79-r.retail.telecomitalia.it[79.19.167.241] 2 Time(s)\r\n         host246-209-dynamic.15-87-r.retail.telecomitalia.it[87.15.209.246] 2 Time(s)\r\n         host248-13-dynamic.1-87-r.retail.telecomitalia.it[87.1.13.248] 2 Time(s)\r\n...\r\n         pool-71-241-246-243.washdc.fios.verizon.net[71.241.246.243] 2 Time(s)\r\n         pool-71-244-163-181.chi01.dsl-w.verizon.net[71.244.163.181] 2 Time(s)\r\n         pool-71-246-128-243.aubnin.fios.verizon.net[71.246.128.243] 2 Time(s)\r\n         pool-71-251-115-130.tampfl.fios.verizon.net[71.251.115.130] 2 Time(s)\r\n         pool-71-251-140-235.cmdnnj.east.verizon.net[71.251.140.235] 2 Time(s)\r\n         pool-71-252-137-81.dllstx.fios.verizon.net[71.252.137.81] 2 Time(s)\r\n         pool-71-99-87-26.tampfl.dsl-w.verizon.net[71.99.87.26] 6 Time(s)\r\n...\r\n         ppp83-237-30-117.pppoe.mtu-net.ru[83.237.30.117] 2 Time(s)\r\n         ppp85-140-146-212.pppoe.mtu-net.ru[85.140.146.212] 2 Time(s)\r\n         ppp85-140-21-109.pppoe.mtu-net.ru[85.140.21.109] 2 Time(s)\r\n         ppp85-140-43-193.pppoe.mtu-net.ru[85.140.43.193] 2 Time(s)\r\n         ppp85-141-174-160.pppoe.mtu-net.ru[85.141.174.160] 4 Time(s)\r\n...\r\n         unknown[116.22.163.196] 6 Time(s)\r\n         unknown[116.45.106.170] 2 Time(s)\r\n         unknown[117.12.65.40] 4 Time(s)\r\n...\r\n\r\n- <\/pre>\n<h3>Conclusion<\/h3>\n<p>N&rsquo;h\u00e9sitez pas, apt-get install postgrey, modif du fichier main.cf et reload de postfix. Ca prend 3 minutes et \u00e7a envoi du gros !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour ceux qui ne connaissent pas, le \u00ab\u00a0Greylisting\u00a0\u00bb est un m\u00e9canisme utile et extr\u00eamement simple \u00e0 mettre en oeuvre pour r\u00e9duire significativement le nombre de spams en entr\u00e9e des serveurs de mails, sans m\u00eame avoir &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,385,82],"tags":[116,120,114,115,118,360,11,99,100,392,117],"class_list":["post-107","post","type-post","status-publish","format-standard","hentry","category-debian","category-mails","category-pl","tag-backup-mx","tag-blacklist","tag-greylist","tag-greylisting","tag-postfix","tag-postgrey","tag-spam","tag-statistiques","tag-stats","tag-whitelist","tag-zombie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Statistiques de greylisting - Le blog de Michauko<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Statistiques de greylisting - Le blog de Michauko\" \/>\n<meta property=\"og:description\" content=\"Pour ceux qui ne connaissent pas, le \u00ab\u00a0Greylisting\u00a0\u00bb est un m\u00e9canisme utile et extr\u00eamement simple \u00e0 mettre en oeuvre pour r\u00e9duire significativement le nombre de spams en entr\u00e9e des serveurs de mails, sans m\u00eame avoir &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Michauko\" \/>\n<meta property=\"article:published_time\" content=\"2008-03-05T15:42:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-10-08T13:26:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png\" \/>\n<meta name=\"author\" content=\"michauko\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"michauko\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/\"},\"author\":{\"name\":\"michauko\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#\\\/schema\\\/person\\\/0cd9f3d9ce4dccc05df81a5b27051ea9\"},\"headline\":\"Statistiques de greylisting\",\"datePublished\":\"2008-03-05T15:42:54+00:00\",\"dateModified\":\"2009-10-08T13:26:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/\"},\"wordCount\":953,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/michauko.org\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/grey1.png\",\"keywords\":[\"backup MX\",\"blacklist\",\"greylist\",\"greylisting\",\"postfix\",\"postgrey\",\"spam\",\"statistiques\",\"stats\",\"whitelist\",\"zombie\"],\"articleSection\":[\"Debian\",\"mails\",\"planet-libre.org\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/\",\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/\",\"name\":\"Statistiques de greylisting - Le blog de Michauko\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/michauko.org\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/grey1.png\",\"datePublished\":\"2008-03-05T15:42:54+00:00\",\"dateModified\":\"2009-10-08T13:26:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#\\\/schema\\\/person\\\/0cd9f3d9ce4dccc05df81a5b27051ea9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#primaryimage\",\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/grey1.png\",\"contentUrl\":\"https:\\\/\\\/michauko.org\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/grey1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/statistiques-de-greylisting-107\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/michauko.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statistiques de greylisting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/\",\"name\":\"Le blog de Michauko\",\"description\":\"Si tu ne comprends pas le titre de l&#039;article, passe ton chemin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/michauko.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#\\\/schema\\\/person\\\/0cd9f3d9ce4dccc05df81a5b27051ea9\",\"name\":\"michauko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g\",\"caption\":\"michauko\"},\"sameAs\":[\"http:\\\/\\\/michauko.org\\\/\"],\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/author\\\/randomized2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Statistiques de greylisting - Le blog de Michauko","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/","og_locale":"fr_FR","og_type":"article","og_title":"Statistiques de greylisting - Le blog de Michauko","og_description":"Pour ceux qui ne connaissent pas, le \u00ab\u00a0Greylisting\u00a0\u00bb est un m\u00e9canisme utile et extr\u00eamement simple \u00e0 mettre en oeuvre pour r\u00e9duire significativement le nombre de spams en entr\u00e9e des serveurs de mails, sans m\u00eame avoir &hellip;","og_url":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/","og_site_name":"Le blog de Michauko","article_published_time":"2008-03-05T15:42:54+00:00","article_modified_time":"2009-10-08T13:26:32+00:00","og_image":[{"url":"https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png","type":"","width":"","height":""}],"author":"michauko","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"michauko","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#article","isPartOf":{"@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/"},"author":{"name":"michauko","@id":"https:\/\/michauko.org\/blog\/#\/schema\/person\/0cd9f3d9ce4dccc05df81a5b27051ea9"},"headline":"Statistiques de greylisting","datePublished":"2008-03-05T15:42:54+00:00","dateModified":"2009-10-08T13:26:32+00:00","mainEntityOfPage":{"@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/"},"wordCount":953,"commentCount":5,"image":{"@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#primaryimage"},"thumbnailUrl":"https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png","keywords":["backup MX","blacklist","greylist","greylisting","postfix","postgrey","spam","statistiques","stats","whitelist","zombie"],"articleSection":["Debian","mails","planet-libre.org"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/","url":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/","name":"Statistiques de greylisting - Le blog de Michauko","isPartOf":{"@id":"https:\/\/michauko.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#primaryimage"},"image":{"@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#primaryimage"},"thumbnailUrl":"https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png","datePublished":"2008-03-05T15:42:54+00:00","dateModified":"2009-10-08T13:26:32+00:00","author":{"@id":"https:\/\/michauko.org\/blog\/#\/schema\/person\/0cd9f3d9ce4dccc05df81a5b27051ea9"},"breadcrumb":{"@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#primaryimage","url":"https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png","contentUrl":"https:\/\/michauko.org\/blog\/wp-content\/uploads\/2008\/03\/grey1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/michauko.org\/blog\/statistiques-de-greylisting-107\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/michauko.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Statistiques de greylisting"}]},{"@type":"WebSite","@id":"https:\/\/michauko.org\/blog\/#website","url":"https:\/\/michauko.org\/blog\/","name":"Le blog de Michauko","description":"Si tu ne comprends pas le titre de l&#039;article, passe ton chemin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/michauko.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/michauko.org\/blog\/#\/schema\/person\/0cd9f3d9ce4dccc05df81a5b27051ea9","name":"michauko","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g","caption":"michauko"},"sameAs":["http:\/\/michauko.org\/"],"url":"https:\/\/michauko.org\/blog\/author\/randomized2\/"}]}},"_links":{"self":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":4,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts\/107\/revisions"}],"predecessor-version":[{"id":787,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts\/107\/revisions\/787"}],"wp:attachment":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/media?parent=107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/categories?post=107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/tags?post=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}