{"id":999,"date":"2010-01-06T07:18:32","date_gmt":"2010-01-06T05:18:32","guid":{"rendered":"http:\/\/michauko.org\/blog\/?p=999"},"modified":"2010-01-05T18:32:27","modified_gmt":"2010-01-05T16:32:27","slug":"nrpe-monitorer-des-linux-avec-nagios","status":"publish","type":"post","link":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/","title":{"rendered":"NRPE : monitorer des Linux avec Nagios"},"content":{"rendered":"<p>Apr\u00e8s <a href=\"https:\/\/michauko.org\/blog\/2009\/10\/07\/mise-en-place-de-nagios\/\">cet article d&rsquo;introduction \u00e0 Nagios quand on n&rsquo;y connait rien \ud83d\ude42<\/a>, o\u00f9 je t\u00e2che de couvrir les bases + le monitoring de machines Windows, essentiellement, voici maintenant le minimum vital pour monitorer un Linux. Quand je dis Linux, je pense Debian. \u00ab\u00a0What else?\u00a0\u00bb comme dirait l&rsquo;autre.<\/p>\n<p>On va donc utiliser NRPE, un \u00e9quivalent Linux (permettez le raccourci) de NSClient++ pour Windows. En gros : un daemon qui permet d&rsquo;ex\u00e9cuter des commandes \u00e0 distance, fournissant en standard la surveillance des tailles des partitions, de la charge CPU, du nombre d&rsquo;utilisateurs, de processus et de zombies. Comme d&rsquo;habitude, Debian a tout packag\u00e9 et il n&rsquo;y a presque rien \u00e0 faire&#8230;<!--more--><\/p>\n<p>Par la suite, on consid\u00e8re une machine nomm\u00e9e \u00ab\u00a0srvnagios\u00a0\u00bb et des machines srv1 et srv2 \u00e0 monitorer. La solution de base Nagios fonctionne, comme expliqu\u00e9 dans l&rsquo;article mentionn\u00e9 plus haut.<\/p>\n<h1>Installation et param\u00e9trage minimum<\/h1>\n<h2>C\u00f4t\u00e9 serveur de monitoring<\/h2>\n<p>Sur le serveur \u00ab\u00a0srvnagios\u00a0\u00bb, on compl\u00e8te l&rsquo;installation existante de Nagios avec le plugin NRPE. Sur Debian, c&rsquo;est le paquet \u00ab\u00a0nagios-nrpe-plugin\u00a0\u00bb. Ca s&rsquo;installe tout seul et la seule chose qu&rsquo;on en retiendra, c&rsquo;est la mise \u00e0 dispo des commandes et fichiers de conf Nafios suivants :<\/p>\n<pre>\r\nsrv_nagios:~# locate check_nrpe\r\n\/etc\/nagios-plugins\/config\/check_nrpe.cfg\r\n\/usr\/lib\/nagios\/plugins\/check_nrpe\r\n<\/pre>\n<h2>C\u00f4t\u00e9 serveur \u00e0 monitorer<\/h2>\n<p>Sur les machines \u00e0 monitorer, on installe le \u00ab\u00a0serveur\u00a0\u00bb NRPE. Sur Debian, c&rsquo;est le paquet \u00ab\u00a0nagios-nrpe-server\u00a0\u00bb. Par d\u00e9pendances, \u00e7a installera tout un bazar, normal.<br \/>\nDeux choses \u00e0 noter :<\/p>\n<pre>srv&#777;1:~# dpkg -L nagios-nrpe-server\r\n[...]\r\n\/etc\/nagios\/nrpe.cfg\r\n\/etc\/nagios\/nrpe_local.cfg\r\n[...]\r\n\/etc\/default\/nagios-nrpe-server\r\n[...]<\/pre>\n<p>Le 3\u00e8 fichier permet de d\u00e9sactiver le mode SSL (pourquoi feriez-vous \u00e7a ?) ou de changer la priorit\u00e9 (\u00ab\u00a0nice\u00a0\u00bb) du daemon.<br \/>\nLe 1er fichier d\u00e9finit plein de param\u00e8tres qu&rsquo;on va \u00e9craser dans \u00ab\u00a0nrpe_local.cfg\u00a0\u00bb, partiellement. Il est bon de survoler le fichier <code>\/etc\/nagios\/nrpe.cfg<\/code> pour y d\u00e9nicher les param\u00e8tres que vous voulez modifier. La bonne pratique semble \u00eatre de le laisser tel quel et d&rsquo;\u00e9craser les valeurs qui vous concernent dans le fichier <code>nrpe_local.cfg<\/code>. Ca doit faciliter le boulot lors d&rsquo;une mont\u00e9e de version. Le 1er fichier \u00ab\u00a0include\u00a0\u00bb le 2\u00e8me \u00e0 la fin.<br \/>\nLe minimum semble \u00eatre de modifier l&rsquo;IP autoris\u00e9e \u00e0 interroger la machine et d&rsquo;y mettre l&rsquo;IP de \u00ab\u00a0srv_nagios\u00a0\u00bb puisque c&rsquo;est lui qui va appeler des commandes :<\/p>\n<pre>srv1:~# cat \/etc\/nagios\/nrpe_local.cfg\r\nallowed_hosts=x.y.z.t<\/pre>\n<p>Sans \u00e7a, seul <code>localhost<\/code> est autoris\u00e9 \u00e0 interroger le daemon. Utile uniquement lorsque Nagios est sur la m\u00eame machine pour se monitorer elle-m\u00eame.<\/p>\n<p>La suite, c&rsquo;est d&rsquo;ajouter les commandes que l&rsquo;on souhaite. Notamment pour la surveillance des partitions de disques. Regardez et comprenez la partie de d\u00e9finition des commandes (statiques ou \u00e0 variables) dans la fin du fichier <code>nrpe.cfg<\/code>. Ca explique la syntaxe et le chapitre suivant :<\/p>\n<h1>Nouvelles commandes<\/h1>\n<p>J&rsquo;ai choisi de cr\u00e9er en dur des commandes pour interroger les partitions. J&rsquo;ai tout hard-cod\u00e9 comme un cochon, plut\u00f4t que de variabiliser. C&rsquo;est un choix. Mais avec la syntaxe lourdingue de Nagios, on est plus \u00e0 quelques copier-coller pr\u00e8s.<br \/>\nJ&rsquo;ai donc ajout\u00e9 dans <code>nrpe_local.cfg<\/code> &#8211; dans le cas d&rsquo;un serveur avec du RAID logiciel &#8211; les commandes suivantes :<\/p>\n<pre>command[check_md1]=\/usr\/lib\/nagios\/plugins\/check_disk -w 20% -c 10% -p \/dev\/md1\r\ncommand[check_md2]=\/usr\/lib\/nagios\/plugins\/check_disk -w 20% -c 10% -p \/dev\/md2\r\ncommand[check_md3]=\/usr\/lib\/nagios\/plugins\/check_disk -w 20% -c 10% -p \/dev\/md3\r\ncommand[check_md6]=\/usr\/lib\/nagios\/plugins\/check_disk -w 20% -c 10% -p \/dev\/md6\r\ncommand[check_md7]=\/usr\/lib\/nagios\/plugins\/check_disk -w 20% -c 10% -p \/dev\/md7<\/pre>\n<p>Dans un cas plus traditionnel, l&rsquo;\u00e9quivalent sera des sda1\/2\/3 ou hda1\/2\/3.<\/p>\n<p>Enfin, le contr\u00f4le du nombre de processus, de la charge etc, est fourni en standard (voir plus bas)<\/p>\n<h1>Tests en commande en ligne<\/h1>\n<p>Depuis le \u00ab\u00a0srv_nagios\u00a0\u00bb, on peut alors &#8211; apr\u00e8s avoir relanc\u00e9 <code>\/etc\/init.d\/nagios-nrpe-server reload<\/code> &#8211; tester nos commandes et aussi se familiariser avec la syntaxe de \u00ab\u00a0check_nrpe\u00a0\u00bb :<\/p>\n<pre>srv_nagios:~# \/usr\/lib\/nagios\/plugins\/check_nrpe -H srv1 -c check_md1 -p 5666\r\nDISK OK - free space: \/boot 170 MB (94% inode=99%);| \/boot=9MB;151;170;0;189\r\n<\/pre>\n<p>Hop, \u00e7a marche, on peut d\u00e9finir tout ce qu&rsquo;il faut dans Nagios.<\/p>\n<h1>Int\u00e9gration dans Nagios<\/h1>\n<p>Je passe sur la d\u00e9finition (au sens Nagios) des machines srv1, srv2 etc. Leurs appartenances \u00e0 des groupes, des templates, des trucs et des bidules de Nagios.<br \/>\nUn exemple simpliste (d\u00e9finition des commandes une \u00e0 une par partition) est donc une longue s\u00e9rie de commandes de ce type \u00e0 int\u00e9grer dans <code>\/etc\/nagios3\/conf.d\/ce_que_vous_voulez.cfg<\/code> :<\/p>\n<pre>define service {\r\n        use     generic-service\r\n        host_name       srv1,srv2 # LE TEST S'APPLIQUERA AUX DEUX MACHINES, ELLES ONT TOUTES LES 2 UN \/dev\/md2\r\n        service_description     NRPE disk md2\r\n        check_command           check_nrpe_1arg!check_md2\r\n}\r\n#[...]\r\ndefine service {\r\n        use     generic-service\r\n        host_name       srv2 # UNE SEULE MACHINE BENEFICIERA DE CE TEST\r\n        service_description     NRPE disk md7\r\n        check_command           check_nrpe_1arg!check_md7\r\n}<\/pre>\n<p>Puis, on d\u00e9clare des commandes pour la charge, les users etc. Cette fois, j&rsquo;ai d\u00e9clar\u00e9 ces tests communs au groupe de machines \u00ab\u00a0nrpe-servers\u00a0\u00bb, dont font partie srv1 et srv2 dans mon cas :<\/p>\n<pre>define service{\r\n        use                     generic-service\r\n        hostgroup_name          nrpe-servers\r\n        service_description     NRPE load\r\n        check_command           check_nrpe_1arg!check_load\r\n}\r\ndefine service{\r\n        use                     generic-service\r\n        hostgroup_name          nrpe-servers\r\n        service_description     NRPE users\r\n        check_command           check_nrpe_1arg!check_users\r\n}\r\ndefine service{\r\n        use                     generic-service\r\n        hostgroup_name          nrpe-servers\r\n        service_description     NRPE zombie\r\n        check_command           check_nrpe_1arg!check_zombie_procs\r\n}\r\ndefine service{\r\n        use                     generic-service\r\n        hostgroup_name          nrpe-servers\r\n        service_description     NRPE procs\r\n        check_command           check_nrpe_1arg!check_total_procs\r\n}<\/pre>\n<p>A noter, dans <code>\/etc\/nagios-plugins\/config\/check_nrpe.cfg<\/code> sur \u00ab\u00a0srv_nagios\u00a0\u00bb, j&rsquo;ai modifi\u00e9 la commande <code>check_nrpe_1arg<\/code> en enlevant le param\u00e8tre de timeout <code>-t 60<\/code>. Je ne sais plus s&rsquo;il y avait une raison valable.<br \/>\nRechargez Nagios et admirez.<\/p>\n<h1>Firewalling<\/h1>\n<p>Pour clore tout \u00e7a, pensez aux restrictions r\u00e9seaux. Pour peu qu&rsquo;il y en ait entre les machines srv_nagios et srv1\/2, pensez \u00e0 ouvrir le port TCP 5666 (si vous ne l&rsquo;avez pas modifi\u00e9). Exemple avec shorewall, dans <code>\/etc\/shorewall\/rules<\/code>, sur la machine monitor\u00e9e \u00ab\u00a0srv1\u00a0\u00bb :<\/p>\n<pre>ACCEPT net:$mon_srvnagios $FW tcp 5666<\/pre>\n<p>Et sur le serveur de supervision \u00ab\u00a0srv_nagios\u00a0\u00bb :<\/p>\n<pre>ACCEPT $FW net:$mon_srv1 $FW tcp 5666<\/pre>\n<p>Avec les IP de mon_srv1 et mon_srvnagios d\u00e9fini dans <code>\/etc\/shorewall\/params<\/code>.<\/p>\n<p>Wala, surveillez bien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s cet article d&rsquo;introduction \u00e0 Nagios quand on n&rsquo;y connait rien \ud83d\ude42, o\u00f9 je t\u00e2che de couvrir les bases + le monitoring de machines Windows, essentiellement, voici maintenant le minimum vital pour monitorer un Linux. &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[82,384],"tags":[325,383,354],"class_list":["post-999","post","type-post","status-publish","format-standard","hentry","category-pl","category-supervision","tag-nagios","tag-nrpe","tag-nsclient"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NRPE : monitorer des Linux avec Nagios - Le blog de Michauko<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NRPE : monitorer des Linux avec Nagios - Le blog de Michauko\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s cet article d&rsquo;introduction \u00e0 Nagios quand on n&rsquo;y connait rien \ud83d\ude42, o\u00f9 je t\u00e2che de couvrir les bases + le monitoring de machines Windows, essentiellement, voici maintenant le minimum vital pour monitorer un Linux. &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Michauko\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-06T05:18:32+00:00\" \/>\n<meta name=\"author\" content=\"michauko\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"michauko\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/\"},\"author\":{\"name\":\"michauko\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#\\\/schema\\\/person\\\/0cd9f3d9ce4dccc05df81a5b27051ea9\"},\"headline\":\"NRPE : monitorer des Linux avec Nagios\",\"datePublished\":\"2010-01-06T05:18:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/\"},\"wordCount\":774,\"commentCount\":1,\"keywords\":[\"nagios\",\"NRPE\",\"NSClient++\"],\"articleSection\":[\"planet-libre.org\",\"supervision\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/\",\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/\",\"name\":\"NRPE : monitorer des Linux avec Nagios - Le blog de Michauko\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#website\"},\"datePublished\":\"2010-01-06T05:18:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#\\\/schema\\\/person\\\/0cd9f3d9ce4dccc05df81a5b27051ea9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/nrpe-monitorer-des-linux-avec-nagios-999\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/michauko.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NRPE : monitorer des Linux avec Nagios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/\",\"name\":\"Le blog de Michauko\",\"description\":\"Si tu ne comprends pas le titre de l&#039;article, passe ton chemin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/michauko.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/michauko.org\\\/blog\\\/#\\\/schema\\\/person\\\/0cd9f3d9ce4dccc05df81a5b27051ea9\",\"name\":\"michauko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g\",\"caption\":\"michauko\"},\"sameAs\":[\"http:\\\/\\\/michauko.org\\\/\"],\"url\":\"https:\\\/\\\/michauko.org\\\/blog\\\/author\\\/randomized2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NRPE : monitorer des Linux avec Nagios - Le blog de Michauko","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/","og_locale":"fr_FR","og_type":"article","og_title":"NRPE : monitorer des Linux avec Nagios - Le blog de Michauko","og_description":"Apr\u00e8s cet article d&rsquo;introduction \u00e0 Nagios quand on n&rsquo;y connait rien \ud83d\ude42, o\u00f9 je t\u00e2che de couvrir les bases + le monitoring de machines Windows, essentiellement, voici maintenant le minimum vital pour monitorer un Linux. &hellip;","og_url":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/","og_site_name":"Le blog de Michauko","article_published_time":"2010-01-06T05:18:32+00:00","author":"michauko","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"michauko","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/#article","isPartOf":{"@id":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/"},"author":{"name":"michauko","@id":"https:\/\/michauko.org\/blog\/#\/schema\/person\/0cd9f3d9ce4dccc05df81a5b27051ea9"},"headline":"NRPE : monitorer des Linux avec Nagios","datePublished":"2010-01-06T05:18:32+00:00","mainEntityOfPage":{"@id":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/"},"wordCount":774,"commentCount":1,"keywords":["nagios","NRPE","NSClient++"],"articleSection":["planet-libre.org","supervision"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/","url":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/","name":"NRPE : monitorer des Linux avec Nagios - Le blog de Michauko","isPartOf":{"@id":"https:\/\/michauko.org\/blog\/#website"},"datePublished":"2010-01-06T05:18:32+00:00","author":{"@id":"https:\/\/michauko.org\/blog\/#\/schema\/person\/0cd9f3d9ce4dccc05df81a5b27051ea9"},"breadcrumb":{"@id":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/michauko.org\/blog\/nrpe-monitorer-des-linux-avec-nagios-999\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/michauko.org\/blog\/"},{"@type":"ListItem","position":2,"name":"NRPE : monitorer des Linux avec Nagios"}]},{"@type":"WebSite","@id":"https:\/\/michauko.org\/blog\/#website","url":"https:\/\/michauko.org\/blog\/","name":"Le blog de Michauko","description":"Si tu ne comprends pas le titre de l&#039;article, passe ton chemin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/michauko.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/michauko.org\/blog\/#\/schema\/person\/0cd9f3d9ce4dccc05df81a5b27051ea9","name":"michauko","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3a8969c185fd0eef3893a15408f3ef1b36a6681a066b1eb32045643c30ba65?s=96&d=mm&r=g","caption":"michauko"},"sameAs":["http:\/\/michauko.org\/"],"url":"https:\/\/michauko.org\/blog\/author\/randomized2\/"}]}},"_links":{"self":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts\/999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/comments?post=999"}],"version-history":[{"count":4,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts\/999\/revisions"}],"predecessor-version":[{"id":1003,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/posts\/999\/revisions\/1003"}],"wp:attachment":[{"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/media?parent=999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/categories?post=999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/michauko.org\/blog\/wp-json\/wp\/v2\/tags?post=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}